{"id":983,"date":"2026-04-10T14:26:16","date_gmt":"2026-04-10T14:26:16","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=983"},"modified":"2026-04-10T14:26:16","modified_gmt":"2026-04-10T14:26:16","slug":"investigan-hurto-en-local-de-yerno-de-horacio-cartes","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/10\/investigan-hurto-en-local-de-yerno-de-horacio-cartes\/","title":{"rendered":"Investigan hurto en local de yerno de Horacio Cartes"},"content":{"rendered":"\n<p>Esta ma\u00f1ana, personal policial de investigaci\u00f3n acudi\u00f3 hasta el local de venta de veh\u00edculos Motor Haus, ubicado sobre la avenida Espa\u00f1a de Asunci\u00f3n, tras la alerta por hurto en una de las oficinas del establecimiento.<\/p>\n\n\n\n<p>Uno de los propietarios relat\u00f3 que pasada las dos de la madrugada de este viernes delincuentes ingresaron a la oficina y se llevaron dinero depositado en una de las cajas fuertes.<\/p>\n\n\n\n<p>El gerente administrativo, Andr\u00e9s Viera, precis\u00f3 al Canal Gen que se llevaron aproximadamente G. 500 millones de la sucursal de la empresa ubicada sobre la conocida avenida capitalina.<\/p>\n\n\n\n<p>Por su parte, el comisario Javier Maldonado, de la unidad de Investigaci\u00f3n, detall\u00f3 que dos a tres personas fueron las que ingresaron al local de venta de veh\u00edculos y se llevaron el dinero.<\/p>\n\n\n\n<p>Tras cometer el hurto, salieron de la oficina y abordaron un veh\u00edculo para darse a la fuga. Adelant\u00f3 que est\u00e1n en una etapa incipiente de la investigaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esta ma\u00f1ana, personal policial de investigaci\u00f3n acudi\u00f3 hasta el local de venta de veh\u00edculos Motor<\/p>\n","protected":false},"author":2,"featured_media":984,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-983","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=983"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/983\/revisions"}],"predecessor-version":[{"id":985,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/983\/revisions\/985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/984"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}