{"id":967,"date":"2026-04-10T12:14:27","date_gmt":"2026-04-10T12:14:27","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=967"},"modified":"2026-04-10T12:14:28","modified_gmt":"2026-04-10T12:14:28","slug":"asume-nueva-jefa-del-departamento-judicial-femenino","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/10\/asume-nueva-jefa-del-departamento-judicial-femenino\/","title":{"rendered":"Asume nueva jefa del Departamento Judicial femenino"},"content":{"rendered":"\n<p>Luego de la destituci\u00f3n de la comisaria principal Nidia Mart\u00ednez como jefa del Departamento Judicial Femenino, el comandante de la Polic\u00eda Nacional, C\u00e9sar Silguero, design\u00f3 a la nueva directora policial.<\/p>\n\n\n\n<p>Se trata de la comisaria principal Sonia Raquel Pav\u00f3n, quien cumpl\u00eda funciones en la Comisar\u00eda 40 Central Thompson de la ciudad de Ypan\u00e9.<\/p>\n\n\n\n<p>El cambio se da en el marco de la pol\u00e9mica generada en torno al caso de la empresaria Dalia L\u00f3pez (55), quien, en una semana, equip\u00f3 su celda vip.<\/p>\n\n\n\n<p>Las irregularidades fueron dadas a conocer en el programa \u201cPy En Vivo\u201d, conducido por \u00d3scar Lovera y Toto Gonz\u00e1lez.<\/p>\n\n\n\n<p>Seg\u00fan se pudo constatar, la empresaria estaba alojada en una celda con comodidades no habituales, como muebles, electrodom\u00e9sticos, aire acondicionado y equipos de gimnasia. Su ba\u00f1o tambi\u00e9n fue completamente remodelado.<\/p>\n\n\n\n<p>El comandante Silguero confirm\u00f3 ante los medios de prensa que no se otorg\u00f3 la autorizaci\u00f3n oficial para realizar las mejoras en la celda, motivo por el cual decidi\u00f3 apartar del cargo a Mart\u00ednez.<\/p>\n\n\n\n<p>La investigaci\u00f3n est\u00e1 a cargo de la Direcci\u00f3n de Asuntos Internos, que desde la ma\u00f1ana del jueves ya inici\u00f3 las primeras diligencias para identificar a todos los involucrados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de la destituci\u00f3n de la comisaria principal Nidia Mart\u00ednez como jefa del Departamento Judicial<\/p>\n","protected":false},"author":2,"featured_media":968,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=967"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/967\/revisions"}],"predecessor-version":[{"id":969,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/967\/revisions\/969"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/968"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}