{"id":882,"date":"2026-04-09T13:33:52","date_gmt":"2026-04-09T13:33:52","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=882"},"modified":"2026-04-09T13:33:52","modified_gmt":"2026-04-09T13:33:52","slug":"emiliano-rolon-fernandez-pide-mayor-presupuesto-para-el-ministerio-publico","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/09\/emiliano-rolon-fernandez-pide-mayor-presupuesto-para-el-ministerio-publico\/","title":{"rendered":"Emiliano Rol\u00f3n Fern\u00e1ndez pide mayor presupuesto para el Ministerio P\u00fablico"},"content":{"rendered":"\n<p>En comunicaci\u00f3n con la radio 1020 AM, el fiscal general del Estado sostuvo que la instituci\u00f3n enfrenta serias dificultades para cubrir cubrir las necesidades m\u00e1s b\u00e1sicas que se requieren para cumplir sus funciones en todo el pa\u00eds.<\/p>\n\n\n\n<p>\u201cDefinitivamente estamos sin la posibilidad de mover lo principal que es la ejecuci\u00f3n de presupuestos y cubrir las necesidades de nuestra instituci\u00f3n. Desde noviembre tenemos muchas dificultades de rendimiento, hay que entender que el Ministerio P\u00fablico tiene que ir ajustando sus piezas e ir creciendo\u201d, expres\u00f3 Rol\u00f3n Fern\u00e1ndez.<\/p>\n\n\n\n<p>En ese sentido, si bien apunt\u00f3 que es un \u201cfirme defensor\u201d de las contrataciones v\u00eda concurso, argument\u00f3 que ciertas tareas muy especializadas, as\u00ed como cubrir puestos en zonas alejadas de nuestro pa\u00eds, no contar\u00edan con postulantes, por lo que inst\u00f3 a optar por m\u00e9todos m\u00e1s directos para estos casos.<\/p>\n\n\n\n<p>\u201cNecesito m\u00e9dicos forenses, llamo a concurso y ese proceso toma un a\u00f1o. No puedo hacer concurso zonal para Fuerte Olimpo, para Capit\u00e1n Bado tampoco, la gente concursa para la capital\u201d, puntualiz\u00f3 el fiscal general.<\/p>\n\n\n\n<p>\u201cEstamos en una situaci\u00f3n dif\u00edcil, esta instituci\u00f3n m\u00e1s que ninguna otra necesita ocupar espacios en cada rinc\u00f3n de la patria, tenemos d\u00e9ficit de fiscales hoy en d\u00eda, 350 agentes deben cubrir todo el pa\u00eds. El a\u00f1o pasado hubo 215 mil denuncias, siendo que necesitamos al menos 300 fiscales m\u00e1s\u201d, sentenci\u00f3 Rol\u00f3n Fern\u00e1ndez.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En comunicaci\u00f3n con la radio 1020 AM, el fiscal general del Estado sostuvo que la<\/p>\n","protected":false},"author":2,"featured_media":883,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-882","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/882","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=882"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/882\/revisions"}],"predecessor-version":[{"id":884,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/882\/revisions\/884"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/883"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=882"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=882"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=882"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}