{"id":491,"date":"2026-04-08T15:54:34","date_gmt":"2026-04-08T15:54:34","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=491"},"modified":"2026-04-08T15:54:34","modified_gmt":"2026-04-08T15:54:34","slug":"cruzada-nacional-recupera-banca-de-chaquenito-y-choca-con-celeste-amarilla","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/08\/cruzada-nacional-recupera-banca-de-chaquenito-y-choca-con-celeste-amarilla\/","title":{"rendered":"Cruzada Nacional recupera banca de \u00abChaque\u00f1ito\u00bb y choca con Celeste Amarilla"},"content":{"rendered":"\n<p>La senadora suplente Gladys Luc\u00eda Mendoza jur\u00f3 este mi\u00e9rcoles en el Senado y pas\u00f3 a ocupar de forma definitiva la banca que dej\u00f3 vacante Javier Vera, expulsado tras el esc\u00e1ndalo de audios comprometedores. Con esta incorporaci\u00f3n, Cruzada Nacional refuerza su bancada y recupera un espacio clave en la C\u00e1mara Alta.<\/p>\n\n\n\n<p>El acto de juramento estuvo marcado por la tensi\u00f3n pol\u00edtica: la senadora liberal Celeste Amarilla cuestion\u00f3 duramente a los suplentes de Cruzada, calific\u00e1ndolos de \u201ccero votos\u201d. La respuesta no se hizo esperar: legisladores como Walter Kobilansky y Yolanda Paredes acusaron a Amarilla de \u201cvivir de calumnias\u201d y de carecer de respeto hacia sus colegas.<\/p>\n\n\n\n<p>El cruce expuso nuevamente la fragilidad de las alianzas en el Congreso y la disputa por legitimidad pol\u00edtica. Mientras Cruzada celebra la recuperaci\u00f3n de su banca, Amarilla insiste en que la agrupaci\u00f3n carece de representatividad real, alimentando un enfrentamiento que promete escalar en las pr\u00f3ximas sesiones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La senadora suplente Gladys Luc\u00eda Mendoza jur\u00f3 este mi\u00e9rcoles en el Senado y pas\u00f3 a<\/p>\n","protected":false},"author":5,"featured_media":492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=491"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/491\/revisions"}],"predecessor-version":[{"id":493,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/491\/revisions\/493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/492"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}