{"id":2214,"date":"2026-04-29T09:33:07","date_gmt":"2026-04-29T12:33:07","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=2214"},"modified":"2026-04-29T09:33:08","modified_gmt":"2026-04-29T12:33:08","slug":"allanamientos-en-4-mojones-dejan-detenidos-y-arsenal","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/29\/allanamientos-en-4-mojones-dejan-detenidos-y-arsenal\/","title":{"rendered":"Allanamientos en 4 Mojones dejan detenidos y arsenal"},"content":{"rendered":"\n<p>Operativo en San Lorenzo permiti\u00f3 detener a dos sospechosos y decomisar armas, chalecos y marihuana tras ataque entre barras en marzo.<\/p>\n\n\n\n<p>Los allanamientos en 4 Mojones dejaron dos detenidos y la incautaci\u00f3n de un arsenal vinculado a presuntos integrantes de la barra de Olimpia. El operativo se realiz\u00f3 en San Lorenzo como parte de una investigaci\u00f3n por un ataque armado ocurrido en marzo.<\/p>\n\n\n\n<p>El procedimiento estuvo a cargo de una comitiva fiscal-policial que intervino simult\u00e1neamente cuatro viviendas en la zona. Los detenidos fueron identificados como C\u00e9sar Antonio Marecos Medina (28) e Iv\u00e1n Alexis P\u00e1ez Irala (26), este \u00faltimo con antecedentes por homicidio doloso y robo agravado.<\/p>\n\n\n\n<p>Las autoridades vinculan el caso con un enfrentamiento ocurrido el 7 de marzo sobre la avenida Avelino Mart\u00ednez. En ese episodio, presuntos barras de Olimpia y Cerro Porte\u00f1o protagonizaron un ataque en la v\u00eda p\u00fablica durante una actividad social.<\/p>\n\n\n\n<p>Durante los allanamientos, los intervinientes decomisaron un rev\u00f3lver, tres rifles y proyectiles de distintos calibres. Adem\u00e1s, incautaron armas blancas, chalecos antibalas y estupefacientes, entre ellos marihuana.<\/p>\n\n\n\n<p>El comisario H\u00e9ctor Molinas, del Departamento de Lucha contra el Crimen Organizado, se\u00f1al\u00f3 que estos elementos son claves para la investigaci\u00f3n. \u201cEstas armas encontradas van a ser sometidas a peritajes para determinar si estuvieron involucradas en otros hechos punibles\u201d, explic\u00f3.<\/p>\n\n\n\n<p>Asimismo, indic\u00f3 que se hallaron vainas servidas de distintos calibres. Seg\u00fan las sospechas, los investigados las conservaban como \u201ctrofeos\u201d tras enfrentamientos con otras facciones.<\/p>\n\n\n\n<p>Uno de los inmuebles allanados pertenecer\u00eda al presunto l\u00edder de la facci\u00f3n investigada. En ese lugar se encontr\u00f3 la mayor cantidad de armas. Sin embargo, el sospechoso no fue ubicado y permanece pr\u00f3fugo.<\/p>\n\n\n\n<p>El fiscal interviniente, H\u00e9ctor Maldonado, inform\u00f3 que la causa incluye los hechos punibles de perturbaci\u00f3n a la paz p\u00fablica, portaci\u00f3n ilegal de armas de fuego y amenaza. Adem\u00e1s, no se descarta la vinculaci\u00f3n de los implicados con otros delitos.<\/p>\n\n\n\n<p>Por otra parte, el Ministerio P\u00fablico logr\u00f3 ubicar una de las viviendas mediante el an\u00e1lisis de im\u00e1genes. En ellas se identificaron prendas de vestir de uno de los sospechosos y una motocicleta utilizada durante el enfrentamiento.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\nhttps:\/\/twitter.com\/ABCCardinal\/status\/2049439097584791870?s=20\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Operativo en San Lorenzo permiti\u00f3 detener a dos sospechosos y decomisar armas, chalecos y marihuana<\/p>\n","protected":false},"author":2,"featured_media":2215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2214","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/2214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=2214"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/2214\/revisions"}],"predecessor-version":[{"id":2216,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/2214\/revisions\/2216"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/2215"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=2214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=2214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=2214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}