{"id":2159,"date":"2026-04-28T12:50:43","date_gmt":"2026-04-28T15:50:43","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=2159"},"modified":"2026-04-28T12:50:44","modified_gmt":"2026-04-28T15:50:44","slug":"asuncion-impactante-atropello-a-peaton-huida-y-heroica-persecucion","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/28\/asuncion-impactante-atropello-a-peaton-huida-y-heroica-persecucion\/","title":{"rendered":"Asunci\u00f3n: Impactante atropello a peat\u00f3n, huida y heroica persecuci\u00f3n"},"content":{"rendered":"\n<p>Un grave accidente de tr\u00e1nsito se registr\u00f3 alrededor de las 08:40 de este martes en el centro de Asunci\u00f3n, cuando la v\u00edctima cruzaba la calle Cerro Cor\u00e1, entre Tacuary y Antequera, donde fue embestida por un autom\u00f3vil Toyota New Vitz, color negro.<\/p>\n\n\n\n<p>Una c\u00e1mara de circuito cerrado capt\u00f3 la escena del violento impacto. La v\u00edctima vol\u00f3 hasta el techo del veh\u00edculo tras el impacto y arrastrada varios metros antes de caer al asfalto, donde qued\u00f3 tendida.<\/p>\n\n\n\n<p>El conductor no detuvo la marcha para ayudar a la v\u00edctima; al contrario, realiz\u00f3 una maniobra para escapar inmediatamente del lugar. En ese \u00ednterin, una camioneta le cerr\u00f3 el paso; sin embargo, logr\u00f3 huir. El otro conductor, que intent\u00f3 frustrar la fuga, no se amilan\u00f3 y lo persigui\u00f3 hasta acorralarlo y entregarlo a las autoridades.<\/p>\n\n\n\n<p>Por fortuna, un m\u00e9dico circulaba detr\u00e1s mismo del veh\u00edculo involucrado, a bordo de una camioneta blanca. Detuvo la marcha y brind\u00f3 los primeros auxilios a la v\u00edctima.<\/p>\n\n\n\n<p>La persona atropellada fue identificada como \u00d3scar Scribano, de 54 a\u00f1os, trabajador del Fondo Nacional de la Cultura y las Artes (Fondec).<\/p>\n\n\n\n<p>Un compa\u00f1ero de trabajo, llamado Ernesto Duarte, relat\u00f3 a NPY que el accidente se produjo cuando el funcionario estaba llegando a su lugar de trabajo, donde incluso escucharon el fuerte impacto y salieron a mirar lo que ocurri\u00f3.<\/p>\n\n\n\n<p>Sus compa\u00f1eros vieron ensangrentado a \u00d3scar Scribano sobre el pavimento hasta que lleg\u00f3 la ambulancia que lo traslad\u00f3 a un centro asistencial.<\/p>\n\n\n\n<p>\u201cDe momento est\u00e1 estable, l\u00facido y le realizan estudios m\u00e9dicos. Est\u00e1 en el Sanatorio Americano, sobre Espa\u00f1a\u201d, inform\u00f3.<\/p>\n\n\n\n<p>Los datos preliminares se\u00f1alan que el conductor implicado cruz\u00f3 en luz roja cuando impact\u00f3 contra la v\u00edctima. El conductor fue identificado como M\u00e1ximo Mendieta Amarilla, de 38 a\u00f1os, quien fue interceptado y detenido a la altura de las calles 13\u00aa Proyectada y M\u00e9xico, de la capital.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">AHORA \ud83d\udd34 Atropell\u00f3 a peat\u00f3n y huy\u00f3<br><br>\ud83d\udd38 Un hombre que cruzaba la calle fue impactado por un autom\u00f3vil sobre la calle Cerro Cor\u00e1 de Asunci\u00f3n.<br><br>\ud83d\udc49\ud83c\udffc El conductor dej\u00f3 tirado al hombre en medio de la calle y escap\u00f3. Una camioneta le choc\u00f3 y le sigui\u00f3.<br><br>\ud83d\udfe0 Segu\u00ed nuestro canal de\u2026 <a href=\"https:\/\/t.co\/n03rZTJpBH\">pic.twitter.com\/n03rZTJpBH<\/a><\/p>&mdash; Monumental AM 1080 (@AM_1080) <a href=\"https:\/\/twitter.com\/AM_1080\/status\/2049112556850012614?ref_src=twsrc%5Etfw\">April 28, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Un grave accidente de tr\u00e1nsito se registr\u00f3 alrededor de las 08:40 de este martes en<\/p>\n","protected":false},"author":2,"featured_media":2160,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/2159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=2159"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/2159\/revisions"}],"predecessor-version":[{"id":2161,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/2159\/revisions\/2161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/2160"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=2159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=2159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=2159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}