{"id":2041,"date":"2026-04-27T10:00:54","date_gmt":"2026-04-27T13:00:54","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=2041"},"modified":"2026-04-27T10:00:55","modified_gmt":"2026-04-27T13:00:55","slug":"mama-de-joven-bombero-asesinado-revelo-que-su-hijo-tenia-amenazas","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/27\/mama-de-joven-bombero-asesinado-revelo-que-su-hijo-tenia-amenazas\/","title":{"rendered":"Mam\u00e1 de joven bombero asesinado revel\u00f3 que su hijo ten\u00eda amenazas"},"content":{"rendered":"\n<p>La mam\u00e1 del bombero asesinado de un disparo en \u00d1emby revel\u00f3 que en el tel\u00e9fono de su hijo hay varios mensajes de amenazas, al igual que en el celular de la actual pareja de la v\u00edctima y apuntan al ex novio de la mujer.<\/p>\n\n\n\n<p>Cinthia N\u00fa\u00f1ez, mam\u00e1 del joven bombero que fue asesinado en \u00d1emby el domingo, revel\u00f3 a radio 1080 AM que su hijo recib\u00eda amenazas y que lo mimos suced\u00eda con la novia, con quien ten\u00eda dos meses de relaci\u00f3n.<\/p>\n\n\n\n<p>\u201cLo poco que yo s\u00e9 es que fue por ajustes. El tipo estaba todav\u00eda celoso por la chica (pareja de su hijo)\u00bb, resalt\u00f3.<\/p>\n\n\n\n<p>Sigui\u00f3 mencionado que su hijo Abel Antonio Duarte N\u00fa\u00f1ez, de 21 a\u00f1os, tiene amenazas en su celular. \u201c\u00c9l tiene amenazas, lo tengo en el tel\u00e9fono de mi hijo, en el tel\u00e9fono de la chica (su pareja)\u201d, prosigui\u00f3.<\/p>\n\n\n\n<p>Cinthia tambi\u00e9n dijo que vio un video donde pudo observar a la novia de su hijo, de nombre Roc\u00edo, hablar con la ex cu\u00f1ada y ex cu\u00f1ado, hermanos de su pareja anterior.<\/p>\n\n\n\n<p>\u201cEn un video que vi ayer, se le ve a la chica (pareja de su hijo) que hablaba con la ex cu\u00f1ada y el ex cu\u00f1ado. Ten\u00eda una relaci\u00f3n hace dos meses con Roc\u00edo\u201d, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p>Sobre lo ocurrido, detall\u00f3 que su hijo sal\u00eda de su trabajo en compa\u00f1\u00eda de Rocio y ya iban a su casa, pero por el camino fue interceptado por un desconocido que, tras preguntar su nombre, le dispar\u00f3.<\/p>\n\n\n\n<p>\u201c\u00c9l sal\u00eda de su trabajo en El Rancho, sal\u00eda acompa\u00f1ado de su pareja para ir a su casa y por el camino, a una cuadra o una cuadra y media, le llegaron. Le preguntaron si era Abel y le dispar\u00f3. Si era un asalto no iban a preguntar su nombre y estos sab\u00edan todo\u201d, mencion\u00f3.<\/p>\n\n\n\n<p>La madre record\u00f3 a su hijo como una persona trabajadora y que ayudaba a todos. Adem\u00e1s, cont\u00f3 que \u00e9l so\u00f1aba con ser polic\u00eda.<\/p>\n\n\n\n<p>\u201cAbel era bombero desde los 16 a\u00f1os. El a\u00f1oraba ser polic\u00eda. Era trabajador, era hijo de abuela, ayudaba mucho por la calle\u201d, lo describi\u00f3.<\/p>\n\n\n\n<p>El joven deja una hija de dos a\u00f1os.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">\ud83d\udd34 Joven bombero es asesinado en \u00d1emby<br><br>\ud83d\udc49\ud83c\udffc Cinthia N\u00fa\u00f1ez, madre de Abel Duarte (21), relat\u00f3 que su hijo fue asesinado a la salida de su trabajo. Indic\u00f3 que estaba recibiendo amenazas por parte de la expareja de su novia.<br><br>\ud83d\udde3\ufe0f &quot;\u00c9l trabaja como guardia de seguridad, sal\u00eda acompa\u00f1ado\u2026 <a href=\"https:\/\/t.co\/K8dQ2FgIZM\">pic.twitter.com\/K8dQ2FgIZM<\/a><\/p>&mdash; Monumental AM 1080 (@AM_1080) <a href=\"https:\/\/twitter.com\/AM_1080\/status\/2048715404269224272?ref_src=twsrc%5Etfw\">April 27, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La mam\u00e1 del bombero asesinado de un disparo en \u00d1emby revel\u00f3 que en el tel\u00e9fono<\/p>\n","protected":false},"author":2,"featured_media":2042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policiales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/2041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=2041"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/2041\/revisions"}],"predecessor-version":[{"id":2043,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/2041\/revisions\/2043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/2042"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=2041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=2041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=2041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}