{"id":1953,"date":"2026-04-25T10:28:42","date_gmt":"2026-04-25T13:28:42","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=1953"},"modified":"2026-04-25T10:28:42","modified_gmt":"2026-04-25T13:28:42","slug":"broma-escolar-termina-en-cirugia-nino-con-perforacion-intestinal","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/25\/broma-escolar-termina-en-cirugia-nino-con-perforacion-intestinal\/","title":{"rendered":"\u201cBroma escolar\u201d termina en cirug\u00eda: ni\u00f1o con perforaci\u00f3n intestinal"},"content":{"rendered":"\n<p>Un alumno de 9 a\u00f1os sufri\u00f3 una <strong>lesi\u00f3n intestinal<\/strong> tras un incidente en clase, cuando un compa\u00f1ero le coloc\u00f3 un l\u00e1piz en el asiento. El hecho gener\u00f3 cuestionamientos de padres y la directora asumi\u00f3 responsabilidad institucional.<\/p>\n\n\n\n<p>La directora de la escuela, <strong>Antonia Barreto<\/strong>, explic\u00f3 que el accidente ocurri\u00f3 de manera repentina: <em>\u201c\u00c9l se levanta para alzar su cuaderno y es ah\u00ed cuando el de al lado le pone el l\u00e1piz. Es cosa que puede ocurrir en cualquier momento, en cualquier lugar\u201d<\/em>.<\/p>\n\n\n\n<p>El ni\u00f1o fue trasladado de inmediato a <strong>primeros auxilios<\/strong>, donde se constat\u00f3 la gravedad de la lesi\u00f3n. La instituci\u00f3n educativa se comprometi\u00f3 a cubrir los gastos m\u00e9dicos, que rondan los <strong>40 millones de guaran\u00edes<\/strong>, en un plazo de 15 d\u00edas.<\/p>\n\n\n\n<p>Barreto pidi\u00f3 comprensi\u00f3n a los padres y asegur\u00f3 que la escuela, junto con la comunidad educativa, asumir\u00e1 la responsabilidad del hecho.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un alumno de 9 a\u00f1os sufri\u00f3 una lesi\u00f3n intestinal tras un incidente en clase, cuando<\/p>\n","protected":false},"author":5,"featured_media":1954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1953","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1953"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1953\/revisions"}],"predecessor-version":[{"id":1955,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1953\/revisions\/1955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1954"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}