{"id":1871,"date":"2026-04-24T08:45:00","date_gmt":"2026-04-24T11:45:00","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=1871"},"modified":"2026-04-24T08:18:03","modified_gmt":"2026-04-24T11:18:03","slug":"consejeros-del-ips-deben-poner-cargos-a-disposicion-aseguran-desde-feprinco","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/24\/consejeros-del-ips-deben-poner-cargos-a-disposicion-aseguran-desde-feprinco\/","title":{"rendered":"Consejeros del IPS deben poner cargos a disposici\u00f3n, aseguran desde Feprinco"},"content":{"rendered":"\n<p>El nuevo presidente del <strong>Instituto de Previsi\u00f3n Social (IPS)<\/strong>, <strong>Isa\u00edas Ricardo Fretes<\/strong>, solicit\u00f3 a los miembros del Consejo de Administraci\u00f3n que pongan sus cargos a disposici\u00f3n, con el objetivo de tener libertad para implementar cambios en la instituci\u00f3n.<\/p>\n\n\n\n<p>La propuesta gener\u00f3 debate interno, ya que el consejero <strong>Jos\u00e9 Emilio Arga\u00f1a<\/strong>, representante del sector empleador, sostuvo que la remoci\u00f3n de cargos es potestad exclusiva del Poder Ejecutivo. Sin embargo, desde la <strong>Federaci\u00f3n de la Producci\u00f3n, la Industria y el Comercio (Feprinco)<\/strong> expresaron su apoyo al pedido de Fretes.<\/p>\n\n\n\n<p>El vicepresidente de Feprinco, <strong>Iv\u00e1n Dumot<\/strong>, calific\u00f3 la solicitud como \u201cabsolutamente razonable\u201d y afirm\u00f3 que el nuevo titular del IPS representa \u201cuna bocanada de aire fresco dentro del tufo a podredumbre que hay en la previsional desde hace tiempo\u201d. A\u00f1adi\u00f3 que todos los consejeros deben colaborar para darle la m\u00e1xima libertad de acci\u00f3n y permitir un \u201ccambio radical\u201d en la instituci\u00f3n.<\/p>\n\n\n\n<p>Fretes, designado esta semana en reemplazo de <strong>Jorge Br\u00edtez<\/strong>, asumi\u00f3 el liderazgo del IPS en medio de cr\u00edticas por la falta de medicamentos, largas esperas y recientes esc\u00e1ndalos en hospitales de la previsional. El presidente <strong>Santiago Pe\u00f1a<\/strong> asegur\u00f3 que le otorg\u00f3 plena libertad para realizar los ajustes necesarios.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El nuevo presidente del Instituto de Previsi\u00f3n Social (IPS), Isa\u00edas Ricardo Fretes, solicit\u00f3 a los<\/p>\n","protected":false},"author":5,"featured_media":1872,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1871"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1871\/revisions"}],"predecessor-version":[{"id":1873,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1871\/revisions\/1873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1872"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}