{"id":1764,"date":"2026-04-22T15:32:13","date_gmt":"2026-04-22T18:32:13","guid":{"rendered":"http:\/\/lanuevavozdigital.com.py\/voz\/?p=1764"},"modified":"2026-04-22T15:40:47","modified_gmt":"2026-04-22T18:40:47","slug":"senado-estira-su-jubilacion-vip-y-sigue-blindada","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/22\/senado-estira-su-jubilacion-vip-y-sigue-blindada\/","title":{"rendered":"Senado estira su Jubilaci\u00f3n VIP y sigue blindada"},"content":{"rendered":"\n<p>El Senado volvi\u00f3 a postergar el tratamiento de las modificaciones a la <strong>Caja Parlamentaria<\/strong>, manteniendo intactos los privilegios de la llamada <strong>\u201cJubilaci\u00f3n VIP\u201d<\/strong>. En la sesi\u00f3n de hoy, tras un debate entre <strong>Dionisio Amarilla<\/strong> y <strong>\u00d3scar Salom\u00f3n<\/strong>, y la ausencia de varios legisladores, el presidente de la C\u00e1mara, <strong>Basilio \u201cBachi\u201d N\u00fa\u00f1ez<\/strong>, resolvi\u00f3 devolver el proyecto a comisiones, dejando el expediente en \u201cfoja cero\u201d.<\/p>\n\n\n\n<p>Amarilla defendi\u00f3 la jubilaci\u00f3n a los <strong>55 a\u00f1os con 15 de aporte<\/strong>, adem\u00e1s de la devoluci\u00f3n de hasta el <strong>95% de los aportes<\/strong>, mientras que Salom\u00f3n plante\u00f3 mantener la versi\u00f3n de Diputados: jubilaci\u00f3n a los <strong>60 a\u00f1os con 20 de aporte<\/strong> y pensi\u00f3n del <strong>80%<\/strong>. Sin mayor\u00eda para ninguna postura, N\u00fa\u00f1ez reprendi\u00f3 a l\u00edderes de bancada por la falta de convocatoria y orden\u00f3 retirar las tarjetas de asistencia de quienes no estaban presentes.<\/p>\n\n\n\n<p>El proyecto, que ya tiene media sanci\u00f3n de Diputados y fue aprobado en general en el Senado, deb\u00eda analizarse art\u00edculo por art\u00edculo. Sin embargo, la falta de acuerdo prolonga la discusi\u00f3n y mantiene los beneficios especiales de los parlamentarios. La reforma, calificada de \u201ccosm\u00e9tica\u201d, introduce algunos recortes en invalidez y pensiones, endurece requisitos para jubilaci\u00f3n anticipada, pero <strong>no elimina los privilegios centrales del sistema<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Senado volvi\u00f3 a postergar el tratamiento de las modificaciones a la Caja Parlamentaria, manteniendo<\/p>\n","protected":false},"author":5,"featured_media":1739,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,4],"tags":[],"class_list":["post-1764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacado","category-politica"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1764"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1764\/revisions"}],"predecessor-version":[{"id":1765,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1764\/revisions\/1765"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1739"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}