{"id":1757,"date":"2026-04-22T15:26:29","date_gmt":"2026-04-22T18:26:29","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=1757"},"modified":"2026-04-22T15:26:29","modified_gmt":"2026-04-22T18:26:29","slug":"cantante-se-enfrento-a-zorro-le-invento-infraccion-pero-no-le-quiso-hacer-boleta","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/22\/cantante-se-enfrento-a-zorro-le-invento-infraccion-pero-no-le-quiso-hacer-boleta\/","title":{"rendered":"Cantante se enfrent\u00f3 a \u00abzorro\u00bb: Le \u00abinvent\u00f3\u00bb infracci\u00f3n, pero no le quiso hacer boleta"},"content":{"rendered":"\n<p>El cantante Jos\u00e9 Viera us\u00f3 sus redes para denunciar p\u00fablicamente que un polic\u00eda de tr\u00e1nsito de la Muni de Asunci\u00f3n le \u00abinvent\u00f3\u00bb una infracci\u00f3n que, seg\u00fan \u00e9l, jam\u00e1s cometi\u00f3. <\/p>\n\n\n\n<p>Le dijo que pas\u00f3 el sem\u00e1foro en rojo, pero Viera asegura que \u00e9l estaba esperando en el sem\u00e1foro en la zona de Mariscal L\u00f3pez Shopping y cuando se puso en verde avanz\u00f3. <\/p>\n\n\n\n<p>Relat\u00f3 que a 100 metros le sali\u00f3 el polic\u00eda al que escrach\u00f3, acompa\u00f1ado de una \u00abse\u00f1ora\u00bb (agente femenino) y que le dijo que pas\u00f3 el sem\u00e1foro en rojo, a lo que \u00e9l sorprendido le respondi\u00f3 que eso es imposible porque esper\u00f3 a que se ponga en verde para avanzar. <\/p>\n\n\n\n<p>\u00abMe dice que me har\u00e1 una multa esperando que le ofrezca algo, pero no amigos, yo no caigo en esa mierda\u00bb, dijo. <\/p>\n\n\n\n<p>En ese momento empez\u00f3 a filmarle con su celular y el polic\u00eda se puso violento, denunci\u00f3. Dijo que sabiendo que \u00e9l no pas\u00f3 en rojo, el zorro no le quiso hacer la boleta de multa y le dej\u00f3 pasar. <\/p>\n\n\n\n<p>De todos modos, Viera dijo que se puso en campa\u00f1a para conseguir las grabaciones de c\u00e1maras en la zona por cualquier cosa, con la seguridad de que el polic\u00eda le quiso invent\u00f3 una infracci\u00f3n buscando sacarle plata. <\/p>\n\n\n\n<p> <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-22-150650.png\" alt=\"\" class=\"wp-image-1758\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"475\" height=\"716\" src=\"https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-22-150628.png\" alt=\"\" class=\"wp-image-1759\" srcset=\"https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-22-150628.png 475w, https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-22-150628-199x300.png 199w\" sizes=\"(max-width: 475px) 100vw, 475px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"445\" height=\"649\" src=\"https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-22-150610.png\" alt=\"\" class=\"wp-image-1760\" srcset=\"https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-22-150610.png 445w, https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Captura-de-pantalla-2026-04-22-150610-206x300.png 206w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/490904846_1215891027212483_5575222811701115377_n-576x1024.jpg\" alt=\"\" class=\"wp-image-1762\" srcset=\"https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/490904846_1215891027212483_5575222811701115377_n-576x1024.jpg 576w, https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/490904846_1215891027212483_5575222811701115377_n-169x300.jpg 169w, https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/490904846_1215891027212483_5575222811701115377_n-768x1365.jpg 768w, https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/490904846_1215891027212483_5575222811701115377_n.jpg 828w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El cantante Jos\u00e9 Viera us\u00f3 sus redes para denunciar p\u00fablicamente que un polic\u00eda de tr\u00e1nsito<\/p>\n","protected":false},"author":6,"featured_media":1758,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-farandula"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1757"}],"version-history":[{"count":2,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1757\/revisions"}],"predecessor-version":[{"id":1763,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1757\/revisions\/1763"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1758"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}