{"id":1751,"date":"2026-04-22T14:38:53","date_gmt":"2026-04-22T17:38:53","guid":{"rendered":"http:\/\/lanuevavozdigital.com.py\/voz\/?p=1751"},"modified":"2026-04-22T14:38:53","modified_gmt":"2026-04-22T17:38:53","slug":"riera-endurece-control-en-estadios-y-conciertos","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/22\/riera-endurece-control-en-estadios-y-conciertos\/","title":{"rendered":"Riera endurece control en estadios y conciertos"},"content":{"rendered":"\n<p>El ministro del Interior, <strong>Enrique Riera<\/strong>, detall\u00f3 las nuevas medidas de seguridad que regir\u00e1n para el acceso a estadios y conciertos en Paraguay. Explic\u00f3 que los <strong>tickets ser\u00e1n personales e intransferibles<\/strong>, eliminando la pr\u00e1ctica de compartir entradas. Adem\u00e1s, se implementar\u00e1 <strong>reconocimiento facial y control biom\u00e9trico<\/strong> para verificar antecedentes judiciales y sanciones administrativas, en el marco del <strong>Registro Nacional de Participantes (RENAE)<\/strong>.<\/p>\n\n\n\n<p>Riera subray\u00f3 la necesidad de una <strong>coordinaci\u00f3n permanente entre Polic\u00eda, Ministerio P\u00fablico y Poder Judicial<\/strong>, se\u00f1alando que sin acusaci\u00f3n fiscal y condena judicial los hechos violentos podr\u00edan repetirse. Tambi\u00e9n anunci\u00f3 el fin de las <strong>entradas de favor<\/strong>, que permit\u00edan el ingreso sin control, y la revisi\u00f3n conjunta de los estadios 24 horas antes de cada evento, tarea que antes reca\u00eda \u00fanicamente en la APF.<\/p>\n\n\n\n<p>El ministro inform\u00f3 que actualmente hay <strong>6 personas detenidas<\/strong>, <strong>9 con pedido de captura<\/strong> y otras <strong>20 en proceso de orden de detenci\u00f3n<\/strong>, como parte de las investigaciones tras los recientes disturbios. Con estas medidas, el Gobierno busca frenar la violencia y garantizar mayor seguridad en espect\u00e1culos deportivos y art\u00edsticos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El ministro del Interior, Enrique Riera, detall\u00f3 las nuevas medidas de seguridad que regir\u00e1n para<\/p>\n","protected":false},"author":5,"featured_media":1752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1751"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1751\/revisions"}],"predecessor-version":[{"id":1753,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1751\/revisions\/1753"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1752"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}