{"id":1721,"date":"2026-04-22T09:55:32","date_gmt":"2026-04-22T12:55:32","guid":{"rendered":"http:\/\/lanuevavozdigital.com.py\/voz\/?p=1721"},"modified":"2026-04-22T09:55:32","modified_gmt":"2026-04-22T12:55:32","slug":"llegan-a-paraguay-los-primeros-rechazados-por-ee-uu-bajo-acuerdo-migratorio","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/22\/llegan-a-paraguay-los-primeros-rechazados-por-ee-uu-bajo-acuerdo-migratorio\/","title":{"rendered":"Llegan a Paraguay los primeros rechazados por EE.UU. bajo acuerdo migratorio"},"content":{"rendered":"\n<p>El Gobierno paraguayo confirm\u00f3 que, en el marco del convenio con Estados Unidos, arribar\u00e1n al pa\u00eds los primeros extranjeros rechazados por las autoridades migratorias norteamericanas.<\/p>\n\n\n\n<p>El director de Migraciones, Jorge Kronawetter; el ministro de la Comisi\u00f3n Nacional de Ap\u00e1tridas y Refugiados, Carlos Vera; y el encargado de negocios de EE.UU., Robert Alter, explicaron que la <strong>Organizaci\u00f3n Internacional para las Migraciones (OIM)<\/strong> ser\u00e1 la responsable de todo el proceso: desde la llegada, hospedaje en un hotel c\u00e9ntrico, hasta el retorno final de estas personas. No habr\u00e1 partida presupuestaria del Estado paraguayo.<\/p>\n\n\n\n<p>Los extranjeros permanecer\u00e1n en r\u00e9gimen de <strong>estancia transitoria<\/strong>, bajo monitoreo de la OIM, con apoyo de la Polic\u00eda Nacional y Migraciones, garantizando su libre tr\u00e1nsito. Uno de los requisitos es que sean de habla hispana y no tengan antecedentes policiales.<\/p>\n\n\n\n<p>Carlos Vera aclar\u00f3 que, durante su estad\u00eda, los migrantes podr\u00e1n solicitar refugio en Paraguay, siguiendo los procedimientos establecidos por la Conare, que incluyen entrevistas y verificaci\u00f3n de datos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno paraguayo confirm\u00f3 que, en el marco del convenio con Estados Unidos, arribar\u00e1n al<\/p>\n","protected":false},"author":5,"featured_media":1722,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1721","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1721"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1721\/revisions"}],"predecessor-version":[{"id":1723,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1721\/revisions\/1723"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1722"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}