{"id":1693,"date":"2026-04-22T06:39:42","date_gmt":"2026-04-22T09:39:42","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=1693"},"modified":"2026-04-22T06:39:43","modified_gmt":"2026-04-22T09:39:43","slug":"golpe-en-tuyucua-francisco-arce-deja-libertad-tras-dura-caida","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/22\/golpe-en-tuyucua-francisco-arce-deja-libertad-tras-dura-caida\/","title":{"rendered":"Golpe en Tuyucu\u00e1: Francisco Arce deja Libertad tras dura ca\u00edda"},"content":{"rendered":"\n<p>La etapa de Francisco Arce al frente de Club Libertad lleg\u00f3 a su final de manera abrupta luego de la contundente goleada sufrida ante Rubio \u00d1u, resultado que termin\u00f3 por desencadenar una decisi\u00f3n que ya ven\u00eda madurando puertas adentro.<\/p>\n\n\n\n<p>El entrenador gumarelo present\u00f3 su renuncia tras el compromiso, marcando as\u00ed el cierre de un ciclo golpeado por los malos resultados y la evidente falta de reacci\u00f3n del equipo en las \u00faltimas presentaciones. La derrota no hizo m\u00e1s que acelerar un desenlace que parec\u00eda inevitable.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>En conferencia de prensa, Arce fue directo y sin rodeos: \u201cSe lo comuniqu\u00e9 al plantel en el entretiempo. La decisi\u00f3n ya la ten\u00eda tomada\u201d, afirm\u00f3, dejando en claro que el rumbo ya estaba definido incluso antes del pitazo final.<\/p>\n\n\n\n<p>Con visible autocr\u00edtica, el ahora exentrenador reconoci\u00f3 no encontrar soluciones al momento futbol\u00edstico del equipo: \u201cYo ya no le encuentro la vuelta, es mejor que venga otra gente\u201d, sentenci\u00f3, evidenciando el desgaste de un proceso que perdi\u00f3 rumbo en semanas recientes.<\/p>\n\n\n\n<p>La Comisi\u00f3n Directiva de Club Libertad acept\u00f3 la renuncia y ya trabaja en la elecci\u00f3n de un nuevo estratega que intente reencauzar el camino del conjunto gumarelo, que ahora deber\u00e1 recomponerse r\u00e1pidamente en medio de un torneo que no da tregua.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"608\" height=\"504\" src=\"https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/IMG_7487.jpeg\" alt=\"\" class=\"wp-image-1695\" srcset=\"https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/IMG_7487.jpeg 608w, https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/IMG_7487-300x249.jpeg 300w\" sizes=\"(max-width: 608px) 100vw, 608px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La etapa de Francisco Arce al frente de Club Libertad lleg\u00f3 a su final de<\/p>\n","protected":false},"author":7,"featured_media":1694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1693","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1693"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1693\/revisions"}],"predecessor-version":[{"id":1696,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1693\/revisions\/1696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1694"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}