{"id":1655,"date":"2026-04-21T10:39:04","date_gmt":"2026-04-21T13:39:04","guid":{"rendered":"http:\/\/lanuevavozdigital.com.py\/voz\/?p=1655"},"modified":"2026-04-21T10:39:05","modified_gmt":"2026-04-21T13:39:05","slug":"diputados-oficialistas-impulsan-a-latorre-como-dupla-de-alliana","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/21\/diputados-oficialistas-impulsan-a-latorre-como-dupla-de-alliana\/","title":{"rendered":"Diputados oficialistas impulsan a Latorre como dupla de Alliana"},"content":{"rendered":"\n<p>La mayor\u00eda de la C\u00e1mara de Diputados oficialista decidi\u00f3 respaldar la postulaci\u00f3n del presidente de Diputados, <strong>Ra\u00fal Latorre<\/strong>, como candidato a vicepresidente en la f\u00f3rmula presidencial de <strong>Pedro Alliana<\/strong> para el 2028. El diputado <strong>Miguel Del Puerto<\/strong> confirm\u00f3 que la propuesta cuenta con amplio apoyo dentro de Honor Colorado y que ser\u00e1 presentada formalmente en los pr\u00f3ximos d\u00edas.<\/p>\n\n\n\n<p>En paralelo, los senadores del movimiento se re\u00fanen hoy para definir su postura respecto a la dupla presidencial, mientras que el <strong>Consejo de Gobernadores<\/strong> tambi\u00e9n busca posicionar a uno de sus integrantes como alternativa. El oficialismo pretende cerrar filas en torno a un candidato de consenso que acompa\u00f1e a Alliana en la chapa.<\/p>\n\n\n\n<p>La definici\u00f3n de la dupla se convierte en un punto clave dentro del oficialismo, ya que marcar\u00e1 el equilibrio de poder entre las bancadas y los gobernadores. La candidatura de Latorre, vista con buenos ojos por la mayor\u00eda de diputados. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mayor\u00eda de la C\u00e1mara de Diputados oficialista decidi\u00f3 respaldar la postulaci\u00f3n del presidente de<\/p>\n","protected":false},"author":5,"featured_media":1656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-1655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1655"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1655\/revisions"}],"predecessor-version":[{"id":1657,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1655\/revisions\/1657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1656"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}