{"id":1245,"date":"2026-04-15T10:53:01","date_gmt":"2026-04-15T13:53:01","guid":{"rendered":"http:\/\/lanuevavozdigital.com.py\/voz\/?p=1245"},"modified":"2026-04-15T10:53:02","modified_gmt":"2026-04-15T13:53:02","slug":"alerta-digital-denuncian-supuesta-filtracion-de-datos-de-la-ande-en-la-web-oscura","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/15\/alerta-digital-denuncian-supuesta-filtracion-de-datos-de-la-ande-en-la-web-oscura\/","title":{"rendered":"Alerta digital: denuncian supuesta filtraci\u00f3n de datos de la ANDE en la web oscura"},"content":{"rendered":"\n<p>A trav\u00e9s de la red social <strong>X<\/strong>, la p\u00e1gina \u201cDark Web Intelligence\u201d inform\u00f3 sobre un presunto anuncio en la web oscura que ofrecer\u00eda una base de datos con informaci\u00f3n de clientes de la <strong>Administraci\u00f3n Nacional de Electricidad (ANDE)<\/strong>. Seg\u00fan la denuncia, se tratar\u00eda de listados con nombres completos, correos electr\u00f3nicos, n\u00fameros de tel\u00e9fono, direcciones f\u00edsicas y mensajes relacionados a solicitudes de servicio.<\/p>\n\n\n\n<p>De confirmarse, la filtraci\u00f3n podr\u00eda ser utilizada para intentos de estafa masiva, como ya ocurri\u00f3 en anteriores casos de exposici\u00f3n de datos en Paraguay. Sin embargo, hasta el momento no se ha podido verificar la autenticidad de la informaci\u00f3n. El director de <strong>Paraguay Ciberseguro<\/strong>, Miguel \u00c1ngel Gaspar, se\u00f1al\u00f3 que parte de los datos coinciden con filtraciones anteriores, aunque no descarta que se trate de un nuevo hecho.<\/p>\n\n\n\n<p>Por su parte, el jefe de Cibercrimen de la Polic\u00eda Nacional, comisario <strong>Diosnel Alarc\u00f3n<\/strong>, indic\u00f3 que no cuentan con informaci\u00f3n oficial sobre esta posible filtraci\u00f3n. Desde la <strong>ANDE<\/strong> a\u00fan no se emiti\u00f3 ning\u00fan comunicado confirmando o desmintiendo la denuncia, mientras expertos advierten sobre la necesidad de reforzar la seguridad digital y la protecci\u00f3n de datos en el pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de la red social X, la p\u00e1gina \u201cDark Web Intelligence\u201d inform\u00f3 sobre un<\/p>\n","protected":false},"author":5,"featured_media":1246,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1245"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1245\/revisions"}],"predecessor-version":[{"id":1247,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1245\/revisions\/1247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1246"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}