{"id":1242,"date":"2026-04-15T10:46:00","date_gmt":"2026-04-15T13:46:00","guid":{"rendered":"http:\/\/lanuevavozdigital.com.py\/voz\/?p=1242"},"modified":"2026-04-15T10:46:02","modified_gmt":"2026-04-15T13:46:02","slug":"furioso-temporal-golpea-neembucu-y-deja-decenas-de-familias-afectadas","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/15\/furioso-temporal-golpea-neembucu-y-deja-decenas-de-familias-afectadas\/","title":{"rendered":"Furioso temporal golpea \u00d1eembuc\u00fa y deja decenas de familias afectadas"},"content":{"rendered":"\n<p>Un fuerte temporal azot\u00f3 entre la noche del martes y la madrugada del mi\u00e9rcoles al Departamento de <strong>\u00d1eembuc\u00fa<\/strong>, causando destrozos en varias localidades. En la ciudad de <strong>Humait\u00e1<\/strong>, al menos 32 viviendas quedaron destechadas, mientras que en <strong>Pilar<\/strong> y <strong>Alberdi<\/strong> se reportaron da\u00f1os en casas y cortes de energ\u00eda el\u00e9ctrica.<\/p>\n\n\n\n<p>Las r\u00e1fagas de viento derribaron \u00e1rboles y dejaron a comunidades enteras sin suministro de la <strong>ANDE<\/strong>, generando preocupaci\u00f3n entre los pobladores. Pese a la magnitud del fen\u00f3meno, las autoridades confirmaron que no se registraron v\u00edctimas, aunque los equipos de emergencia contin\u00faan verificando la situaci\u00f3n.<\/p>\n\n\n\n<p>La <strong>Gobernaci\u00f3n de \u00d1eembuc\u00fa<\/strong> despleg\u00f3 brigadas para asistir a las familias damnificadas y evaluar los da\u00f1os. Meteorolog\u00eda advirti\u00f3 que el sistema de tormentas podr\u00eda persistir durante la jornada, con lluvias intensas y descargas el\u00e9ctricas en gran parte del territorio nacional. <\/p>\n\n\n\n<p>Foto: Juan Jos\u00e9 Brull.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un fuerte temporal azot\u00f3 entre la noche del martes y la madrugada del mi\u00e9rcoles al<\/p>\n","protected":false},"author":5,"featured_media":1243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1242"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1242\/revisions"}],"predecessor-version":[{"id":1244,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1242\/revisions\/1244"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1243"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}