{"id":1149,"date":"2026-04-14T00:11:41","date_gmt":"2026-04-14T00:11:41","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=1149"},"modified":"2026-04-14T00:11:41","modified_gmt":"2026-04-14T00:11:41","slug":"la-muni-de-lambare-ordeno-cierre-de-bar-pz10-y-pablo-zeballos-desafia-al-intendente","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/14\/la-muni-de-lambare-ordeno-cierre-de-bar-pz10-y-pablo-zeballos-desafia-al-intendente\/","title":{"rendered":"La Muni de Lambar\u00e9 orden\u00f3 cierre de Bar PZ10 y Pablo Zeballos desaf\u00eda al intendente"},"content":{"rendered":"\n<p><br>El viernes pasado, un juez de faltas de la Muni de Lambar\u00e9 orden\u00f3 el cierre temporal del Bar PZ10 de Pablo Zeballos. El ex jugador calific\u00f3 de persecuci\u00f3n pol\u00edtica la decisi\u00f3n de la administraci\u00f3n del intendente Guido Gonz\u00e1lez, por haberse lanzado como candidato a concejal. <\/p>\n\n\n\n<p>\u00abMuchas gracias Intendente Guido Gonz\u00e1lez por cerrar el local, sab\u00eda que quer\u00edas llegar a eso y te agradezco por darme la raz\u00f3n a tu nefasta administraci\u00f3n, a tu ignorancia, inoperancia y soberbia\u00bb, empez\u00f3 dici\u00e9ndole en una carta que le dirigi\u00f3 a trav\u00e9s de las redes. <\/p>\n\n\n\n<p>\u00abSiento mucho que tus empleados se presten a semejante barbaridad, la jefa de comercio, el de PCI y ni qu\u00e9 decir una jueza de por medio. Yo no voy a dejar tiradas a las personas que trabajan conmigo y voy a seguir demostrando que sos una verg\u00fcenza, porque despu\u00e9s de mis publicaciones est\u00e1s autorizando a esta resoluci\u00f3n\u00bb, dijo.<br><\/p>\n\n\n\n<p>El ex jugador denunci\u00f3 que el intendente le mand\u00f3 decir a trav\u00e9s de dos personas que renuncie a su candidatura, para que despu\u00e9s pueda hacer lo que quiera. <br><\/p>\n\n\n\n<p>\u00abTengo todo presentado, la resoluci\u00f3n desde el 2018, la aprobaci\u00f3n de planos, los pagos correspondientes y que ustedes quieran esconder del expediente es otra cosa (muy grave por cierto). Ante esto me reservo el derecho a accionar en contra del o los responsables\u00bb, sigui\u00f3.<br><br>\u00ab\u00bfDe qu\u00e9 tienen miedo vos y tus concejales que nunca hicieron nada y viven del municipio?<br>Por eso LAMBAR\u00c9 est\u00e1 como est\u00e1 y a mi parecer tu conducta no est\u00e1 alineada con los principios del movimiento pol\u00edtico al que represent\u00e1s\u00bb, remat\u00f3. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Muchas-gracias-Intendente-@guidogonzalezd-por-cerrar-el-local-sabia-que-querias-llegar-a-eso-y-768x1024.webp\" alt=\"\" class=\"wp-image-1150\" srcset=\"https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Muchas-gracias-Intendente-@guidogonzalezd-por-cerrar-el-local-sabia-que-querias-llegar-a-eso-y-768x1024.webp 768w, https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Muchas-gracias-Intendente-@guidogonzalezd-por-cerrar-el-local-sabia-que-querias-llegar-a-eso-y-225x300.webp 225w, https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Muchas-gracias-Intendente-@guidogonzalezd-por-cerrar-el-local-sabia-que-querias-llegar-a-eso-y-450x600.webp 450w, https:\/\/lanuevavozdigital.com.py\/voz\/wp-content\/uploads\/2026\/04\/Muchas-gracias-Intendente-@guidogonzalezd-por-cerrar-el-local-sabia-que-querias-llegar-a-eso-y.webp 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El viernes pasado, un juez de faltas de la Muni de Lambar\u00e9 orden\u00f3 el cierre<\/p>\n","protected":false},"author":6,"featured_media":1151,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-farandula"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1149"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1149\/revisions"}],"predecessor-version":[{"id":1152,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1149\/revisions\/1152"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1151"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}