{"id":1146,"date":"2026-04-13T23:56:50","date_gmt":"2026-04-13T23:56:50","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=1146"},"modified":"2026-04-13T23:58:37","modified_gmt":"2026-04-13T23:58:37","slug":"eve-gomez-hablo-de-su-historia-con-un-locutor-casado-y-aseguro-que-no-llegaron-a-la-cama","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/13\/eve-gomez-hablo-de-su-historia-con-un-locutor-casado-y-aseguro-que-no-llegaron-a-la-cama\/","title":{"rendered":"Eve G\u00f3mez habl\u00f3 de su historia con un locutor casado y asegur\u00f3 que no llegaron a la cama"},"content":{"rendered":"\n<p>La locutora Eve G\u00f3mez estuvo en el programa de Pelusa Rubin en Latele y habl\u00f3 sobre su relaci\u00f3n que cruz\u00f3 levemente la l\u00ednea de la amistad con un locutor casado. <\/p>\n\n\n\n<p>Coment\u00f3 que esa relaci\u00f3n cruz\u00f3 levemente la l\u00ednea de la amistad, pero asegur\u00f3 que no llegaron a la cama. \u201cAlgunas personas me dicen que estoy dolida porque \u00e9l no la dej\u00f3, pero yo nunca quise eso. Yo sab\u00eda lo que me esperaba; si dejaba a esa persona para estar conmigo, despu\u00e9s iba a venir otra, y yo no quiero vivir con inseguridad toda mi vida\u201d, dijo.<\/p>\n\n\n\n<p>Si bien el locutor ahora est\u00e1 casado, ella aclar\u00f3 que la historia es de antes de la boda de \u00e9l. Dijo que, incluso, cuand\u00f3 \u00e9l se iba a casar le lleg\u00f3 a preguntar c\u00f3mo le quedaba su traje.  <\/p>\n\n\n\n<p>\u201cMe pregunt\u00f3 qu\u00e9 tal le qued\u00f3 su traje y le dije que espectacular, que el blanco le quedaba muy bien. Despu\u00e9s quedamos como amigos, nunca tuve problemas con \u00e9l\u201d, dijo.<br><\/p>\n\n\n\n<p>Cont\u00f3 que las cosas se complicaron cuando la esposa se enter\u00f3 del v\u00ednculo que ten\u00edan, que eso desemboc\u00f3 en una persecuci\u00f3n contra ella, lo que hizo que todo saliera a la luz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La locutora Eve G\u00f3mez estuvo en el programa de Pelusa Rubin en Latele y habl\u00f3<\/p>\n","protected":false},"author":6,"featured_media":1147,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-farandula"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1146"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1146\/revisions"}],"predecessor-version":[{"id":1148,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1146\/revisions\/1148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1147"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}