{"id":1060,"date":"2026-04-11T20:44:05","date_gmt":"2026-04-11T20:44:05","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=1060"},"modified":"2026-04-11T20:44:05","modified_gmt":"2026-04-11T20:44:05","slug":"canela-dio-su-primer-paseo-tras-recuperarse-de-segunda-operacion-y-muestra-mejoria","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/11\/canela-dio-su-primer-paseo-tras-recuperarse-de-segunda-operacion-y-muestra-mejoria\/","title":{"rendered":"Canela dio su primer paseo tras recuperarse de segunda operaci\u00f3n y muestra mejor\u00eda"},"content":{"rendered":"\n<p>En un emotivo video, la organizaci\u00f3n Olfateando Huellas se puede ver la mejor\u00eda de Canela, la perrita que hab\u00eda perdido la mand\u00edbula a causa de la explosi\u00f3n de un ceboll\u00f3n. La canina finalmente se encuentra dando un paseo con una incre\u00edble energ\u00eda moviendo la cola, luego de realizarse una segunda cirug\u00eda debido a que su pr\u00f3tesis se le movi\u00f3 de lugar.<\/p>\n\n\n\n<p>\u201cCanela, mi asistente personal, me acompa\u00f1a a todos lados moviendo la colita y muy feliz. Hoy le toc\u00f3 acompa\u00f1arme a Defensa Animal y ella misma le dio mesa de entrada a la documentaci\u00f3n que pidi\u00f3 el director de Defensa Animal\u201d, expresa parte de la publicaci\u00f3n en las redes sociales de la organizaci\u00f3n.<\/p>\n\n\n\n<p>Seguidamente, la animalera y fundadora de Olfateando Huellas, Diana Camarasa, mencion\u00f3 que tuvo una reuni\u00f3n con el director de la Direcci\u00f3n de Nacional de Defensa, Salud y Bienestar Animal, H\u00e9ctor Luis Rub\u00edn, en donde trazaron las bases de futuros proyectos conjuntos para dar seguimiento a la propuesta presentada ante el Comit\u00e9 Multidisciplinario de la Direcci\u00f3n Nacional de Defensa, Salud y Bienestar Animal.<\/p>\n\n\n\n<p>\u201cCanela no habla pero por medio de su expresi\u00f3n sent\u00ed que ella fue a pedir Justicia y mostrar que ella es un milagro viviente. Se sent\u00f3 y le mir\u00f3 a los ojos al director jur\u00eddico y al director ejecutivo como pidiendo en verdad Justicia en su caso\u201d, expres\u00f3 Camarasa.<\/p>\n\n\n\n<p>El m\u00e9dico veterinario Luis Ferrer afirm\u00f3 que Canelita se encuentra en estado de recuperaci\u00f3n y que en todos los informes realizados su pron\u00f3stico m\u00e9dico es favorable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un emotivo video, la organizaci\u00f3n Olfateando Huellas se puede ver la mejor\u00eda de Canela,<\/p>\n","protected":false},"author":2,"featured_media":1061,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacionales"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1060"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1060\/revisions"}],"predecessor-version":[{"id":1062,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1060\/revisions\/1062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1061"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}