{"id":1001,"date":"2026-04-10T17:31:41","date_gmt":"2026-04-10T17:31:41","guid":{"rendered":"https:\/\/lanuevavozdigital.com.py\/voz\/?p=1001"},"modified":"2026-04-10T17:31:41","modified_gmt":"2026-04-10T17:31:41","slug":"la-despedida-de-los-eagles-arrasan-y-tuvieron-que-agregar-shows-hasta-mayo","status":"publish","type":"post","link":"https:\/\/lanuevavozdigital.com.py\/voz\/2026\/04\/10\/la-despedida-de-los-eagles-arrasan-y-tuvieron-que-agregar-shows-hasta-mayo\/","title":{"rendered":"\u00a1La despedida de los Eagles! Arrasan y tuvieron que agregar shows hasta mayo"},"content":{"rendered":"\n<p>Los Eagles arrasan con sus shows de despedida en Estados Unidos. Solamente en Las Vegas, en un mismo escenario, en The Sphere, ya hicieron 50 shows desde enero y tuvieron que agregar 8 m\u00e1s, que cerrar\u00e1n ma\u00f1ana. <\/p>\n\n\n\n<p>El anfiteatro con una vista impresionante hacia las monta\u00f1as, tiene capacidad para 20.000 personas. Por ahora, tienen marcado que despu\u00e9s de sus shows en Atlanta y Vashville, el 18 de mayo se despedir\u00e1n en forma definitiva con un concierto en el Globe Life Field, Arlington (Texas).<\/p>\n\n\n\n<p>Su gira se llama \u00abThe Long Goodbye\u00bb y arranc\u00f3 en el 2017, cuando se reagruparon en el 2017 tras la muerte de Glenn Frey en 2016. Actualmente la integran Don Henley, Joe Walsh, Timothy B. Schmit, Vince Gill y Deacon Frey.<\/p>\n\n\n\n<p>El grupo se separ\u00f3 en 1980 para volverse a reunir en 1994, per\u00edodo que dur\u00f3 hasta 2016, en que muri\u00f3 uno de sus fundadores, el vocalista Glenn Frey. The Eagles, banda formada en 1971 en Los \u00c1ngeles, tiene varios \u00e9xitos, pero su \u00edcono mundial es Hotel California. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"tr\" dir=\"ltr\">Eagles grubu, Las Vegas&#39;da verdi\u011fi konserde \u201cHotel California\u201d \u015fark\u0131s\u0131n\u0131 b\u00f6yle seslendirdi.<br><br>Adamlar\u0131n yaratt\u0131\u011f\u0131 atmosfere bakar m\u0131s\u0131n\u0131z l\u00fctfen <a href=\"https:\/\/t.co\/Bl5zExQRBU\">pic.twitter.com\/Bl5zExQRBU<\/a><\/p>&mdash; nerde o eski \u015fark\u0131lar (@eskisarkiIar) <a href=\"https:\/\/twitter.com\/eskisarkiIar\/status\/2042369920319537378?ref_src=twsrc%5Etfw\">April 9, 2026<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Eagles arrasan con sus shows de despedida en Estados Unidos. Solamente en Las Vegas,<\/p>\n","protected":false},"author":6,"featured_media":1011,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-farandula"],"_links":{"self":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/comments?post=1001"}],"version-history":[{"count":1,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1001\/revisions"}],"predecessor-version":[{"id":1012,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/posts\/1001\/revisions\/1012"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media\/1011"}],"wp:attachment":[{"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/media?parent=1001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/categories?post=1001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lanuevavozdigital.com.py\/voz\/wp-json\/wp\/v2\/tags?post=1001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}